{"id":20,"date":"2026-08-03T12:57:56","date_gmt":"2026-08-03T12:57:56","guid":{"rendered":"http:\/\/proresolve-dev.local\/us\/home\/"},"modified":"2026-08-03T12:57:56","modified_gmt":"2026-08-03T12:57:56","slug":"home","status":"publish","type":"page","link":"https:\/\/proresolvespms.com\/us\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-home-us.php","meta":{"_yoast_wpseo_focuskw":"SPM supplements","_yoast_wpseo_title":"ProResolve | SPM Supplements Backed by Science","_yoast_wpseo_metadesc":"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*","_yoast_wpseo_meta-robots-noindex":"","footnotes":""},"class_list":["post-20","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ProResolve | SPM Supplements Backed by Science<\/title>\n<meta name=\"description\" content=\"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proresolvespms.com\/us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ProResolve | SPM Supplements Backed by Science\" \/>\n<meta property=\"og:description\" content=\"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proresolvespms.com\/us\/\" \/>\n<meta property=\"og:site_name\" content=\"ProResolve\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proresolvespms.com\/us\/wp-content\/uploads\/sites\/2\/2026\/08\/home-hero-poster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\",\"url\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\",\"name\":\"ProResolve | SPM Supplements Backed by Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#website\"},\"datePublished\":\"2026-08-03T12:57:56+00:00\",\"description\":\"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\",\"name\":\"ProResolve\",\"description\":\"SPM supplements backed by science\",\"publisher\":{\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#organization\",\"name\":\"Azur Global Nutrition\",\"url\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/08\\\/logo-proresolve-black.png\",\"contentUrl\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/08\\\/logo-proresolve-black.png\",\"width\":372,\"height\":58,\"caption\":\"ProResolve\"},\"image\":{\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"legalName\":\"Azur Global Nutrition\",\"alternateName\":[\"Azur GN\",\"ProResolve\"],\"brand\":{\"@type\":\"Brand\",\"@id\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/#brand-proresolve\",\"name\":\"ProResolve\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/azur-global-nutrition\",\"https:\\\/\\\/www.youtube.com\\\/@azurglobalnutrition371\",\"https:\\\/\\\/www.instagram.com\\\/proresolvespms\\\/\"],\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"Solutex GC\",\"url\":\"https:\\\/\\\/solutexcorp.com\\\/\",\"sameAs\":\"https:\\\/\\\/solutexcorp.com\\\/\"},\"email\":\"proresolveusa@proresolvespms.com\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"customer service\",\"email\":\"proresolveusa@proresolvespms.com\",\"url\":\"https:\\\/\\\/proresolvespms.com\\\/us\\\/contact-us\\\/\",\"availableLanguage\":[\"Spanish\",\"English\"],\"areaServed\":\"US\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ProResolve | SPM Supplements Backed by Science","description":"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proresolvespms.com\/us\/","og_locale":"en_US","og_type":"article","og_title":"ProResolve | SPM Supplements Backed by Science","og_description":"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*","og_url":"https:\/\/proresolvespms.com\/us\/","og_site_name":"ProResolve","og_image":[{"width":1920,"height":949,"url":"https:\/\/proresolvespms.com\/us\/wp-content\/uploads\/sites\/2\/2026\/08\/home-hero-poster.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proresolvespms.com\/us\/","url":"https:\/\/proresolvespms.com\/us\/","name":"ProResolve | SPM Supplements Backed by Science","isPartOf":{"@id":"https:\/\/proresolvespms.com\/us\/#website"},"datePublished":"2026-08-03T12:57:56+00:00","description":"SPM supplements formulated with Lipinova\u00ae, a patented ingredient standardized in specialized pro-resolving mediators from marine omega-3 oils.*","breadcrumb":{"@id":"https:\/\/proresolvespms.com\/us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proresolvespms.com\/us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proresolvespms.com\/us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proresolvespms.com\/us\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/proresolvespms.com\/us\/#website","url":"https:\/\/proresolvespms.com\/us\/","name":"ProResolve","description":"SPM supplements backed by science","publisher":{"@id":"https:\/\/proresolvespms.com\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proresolvespms.com\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proresolvespms.com\/us\/#organization","name":"Azur Global Nutrition","url":"https:\/\/proresolvespms.com\/us\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proresolvespms.com\/us\/#\/schema\/logo\/image\/","url":"https:\/\/proresolvespms.com\/us\/wp-content\/uploads\/sites\/2\/2026\/08\/logo-proresolve-black.png","contentUrl":"https:\/\/proresolvespms.com\/us\/wp-content\/uploads\/sites\/2\/2026\/08\/logo-proresolve-black.png","width":372,"height":58,"caption":"ProResolve"},"image":{"@id":"https:\/\/proresolvespms.com\/us\/#\/schema\/logo\/image\/"},"legalName":"Azur Global Nutrition","alternateName":["Azur GN","ProResolve"],"brand":{"@type":"Brand","@id":"https:\/\/proresolvespms.com\/us\/#brand-proresolve","name":"ProResolve"},"sameAs":["https:\/\/www.linkedin.com\/company\/azur-global-nutrition","https:\/\/www.youtube.com\/@azurglobalnutrition371","https:\/\/www.instagram.com\/proresolvespms\/"],"parentOrganization":{"@type":"Organization","name":"Solutex GC","url":"https:\/\/solutexcorp.com\/","sameAs":"https:\/\/solutexcorp.com\/"},"email":"proresolveusa@proresolvespms.com","contactPoint":{"@type":"ContactPoint","contactType":"customer service","email":"proresolveusa@proresolvespms.com","url":"https:\/\/proresolvespms.com\/us\/contact-us\/","availableLanguage":["Spanish","English"],"areaServed":"US"}}]}},"_links":{"self":[{"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/pages\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/pages\/20\/revisions"}],"wp:attachment":[{"href":"https:\/\/proresolvespms.com\/us\/wp-json\/wp\/v2\/media?parent=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}